{"id":115877,"date":"2020-08-12T19:57:16","date_gmt":"2020-08-12T19:57:16","guid":{"rendered":"https:\/\/sitiwebsavona.it\/studiowiki\/inova\/?p=115877"},"modified":"2022-12-08T17:35:55","modified_gmt":"2022-12-08T17:35:55","slug":"leditoriale-elogio-alla-leggerezza","status":"publish","type":"post","link":"https:\/\/studiowiki.it\/inova\/leditoriale-elogio-alla-leggerezza\/","title":{"rendered":"Elogio alla leggerezza"},"content":{"rendered":"<p>Per augurarvi buone ferie abbiamo pensato a un numero speciale. Che contiene un gioco. Un gioco per restituire un po\u2019 di tempo e un po\u2019 di spazio all\u2019immaginazione e alla sfida. Giocare stimola insight innovativi e creativi, allo stesso modo del silenzio, dell\u2019inattivit\u00e0, del vuoto apparente dall\u2019impegno cosiddetto \u201cproduttivo\u201d.<\/p>\n<p>Cos\u00ec, le nostre foto realizzate a marzo, in pieno lockdown, da casa nostra per la campagna nazionale firmata da Studiowiki \u201cThe Show must go home\u201d oggi diventano gi\u00e0 qualcos\u2019altro\u2026 perch\u00e9 lo show \u00e8 andato avanti e adesso non bisogna perdere la leggerezza. La capacit\u00e0 di non prendersi troppo sul serio. Il gioco consiste nell\u2019associare a ognuno di noi la citazione scelta. Giochiamo! Buona lettura e buona estate!<\/p>\n<p>P.S. A proposito, noi di Inova ci stiamo dividendo i compiti delle vacanze. Noi leggeremo qualcosa\u2026e voi? Lista<\/p>\n","protected":false},"excerpt":{"rendered":"Per augurarvi buone ferie abbiamo pensato a un numero speciale. Che contiene un gioco. Un gioco per restituire&hellip;\n","protected":false},"author":4,"featured_media":115879,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"0","_seopress_titles_title":"","_seopress_titles_desc":"59esima edizione del TTG di Rimini 2022, tenutasi dal 11 al 13 ottobre nei padiglioni della fiera romagnola: proviamo a tirare due somme.","_seopress_robots_index":"","csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[89,227],"tags":[189,218],"class_list":{"0":"post-115877","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-editoriale","8":"category-inova","9":"tag-editoriale","10":"tag-inova-16","11":"cs-entry","12":"cs-video-wrap"},"_links":{"self":[{"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/posts\/115877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/comments?post=115877"}],"version-history":[{"count":3,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/posts\/115877\/revisions"}],"predecessor-version":[{"id":116024,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/posts\/115877\/revisions\/116024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/media\/115879"}],"wp:attachment":[{"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/media?parent=115877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/categories?post=115877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/tags?post=115877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}