{"id":112131,"date":"2021-09-17T10:57:42","date_gmt":"2021-09-17T10:57:42","guid":{"rendered":"https:\/\/www.studiowiki.it\/?p=112131"},"modified":"2022-11-23T18:49:40","modified_gmt":"2022-11-23T18:49:40","slug":"inova-n-41-accessibilita-cose-e-come-funziona","status":"publish","type":"post","link":"https:\/\/studiowiki.it\/inova\/inova-n-41-accessibilita-cose-e-come-funziona\/","title":{"rendered":"Accessibilit\u00e0: cos&#8217;\u00e8 e come funziona"},"content":{"rendered":"<p>Le persone con disabilit\u00e0, secondo la pubblicazione ISTAT <em>\u201cConoscere il mondo della disabilit\u00e0\u201d<\/em>, del 2019, sono 3,1 milioni; ma il numero di siti che consente l\u2019utilizzo dei contenuti da parte loro, con screen reader o altri strumenti di navigazione alternativi ai browser tradizionali \u00e8 molto limitato.<\/p>\n<p>Il potere del web risiede, fin dalla sua nascita, nell\u2019universalit\u00e0. Per sua natura la rete \u00e8 progettata per funzionare per tutti. Il web dovrebbe poter eliminare le barriere alla comunicazione e interazione che molte persone disabili affrontano nel mondo fisico, ma quando i siti web vengono progettati male possono creare altre barriere che escludono, ancora una volta, un determinato gruppo.<\/p>\n<p>Con il termine accessibilit\u00e0 si intende la possibilit\u00e0 di fruizione dei contenuti web a tutti gli utenti, senza discriminazioni. L\u2019obiettivo primario dell\u2019accessibilit\u00e0 sta nell\u2019eliminare le barriere architettoniche informatiche e quindi tutti gli ostacoli che le persone affette da disabilit\u00e0 incontrano ogni giorno quando utilizzano determinati servizi presenti in rete, e pi\u00f9 in generale offrire pari condizioni a tutti gli utenti.<\/p>\n<p>\u00c8 necessario sottolineare che l\u2019accessibilit\u00e0 non riguarda solo le persone che soffrono di disabilit\u00e0 ma, in senso esteso, riguarda tutti gli utenti: dagli anziani, ai dislessici a coloro che hanno disabilit\u00e0 temporanea, passando per chiunque sia in mobilit\u00e0 o dispone di connessioni lente. L\u2019accessibilit\u00e0 \u00e8 il tentativo di fornire a tutte le persone le stesse opportunit\u00e0 di fruizione.<\/p>\n<p>L&#8217;accessibilit\u00e0\u00a0\u00e8 un requisito obbligatorio nei siti della Pubblica Amministrazione\u00a0ed \u00e8 regolamentata da una serie di leggi tra le quali la Direttiva UE 2016\/2102 del Parlamento Europeo, pubblicata il 26 ottobre 2016 e relativa a <em>\u201cAccessibilit\u00e0 dei siti web e delle applicazioni mobili degli enti pubblici\u201d.<\/em> Dal 23 settembre 2020 tutti i siti della Pubblica Amministrazione pubblicati prima del 23 settembre 2018 devono adeguarsi alle linee di accessibilit\u00e0, pubblicare la <em>&#8220;Dichiarazione di Accessibilit\u00e0&#8221;<\/em> e consentire l&#8217;invio di segnalazioni da parte degli utenti.<\/p>\n<p>Gli obblighi in materia di accessibilit\u00e0 sono:<\/p>\n<ul>\n<li><strong>Conformarsi ai requisiti tecnici previsti dalla Legge Stanca<\/strong><\/li>\n<\/ul>\n<p><em>(La Legge c.d. Stanca riconosce e tutela il diritto di accesso ai servizi informatici e telematici della pubblica amministrazione da parte dei disabili, garantendo il rispetto del principio fondamentale di pari opportunit\u00e0 e l\u2019accesso dei cittadini disabili ai servizi della pubblica amministrazione. L\u2019obiettivo della Legge \u00e8 l\u2019abbattimento delle barriere digitali che limitano o impediscono l\u2019accesso agli strumenti\u00a0ICT\u00a0da parte dei disabili)<\/em><\/p>\n<ul>\n<li>Svolgere una<strong> costante attivit\u00e0 di monitoraggio e auto-valutazione sull\u2019accessibilit\u00e0<\/strong><\/li>\n<li>Pubblicare annualmente gli <strong><em>obiettivi di accessibilit\u00e0<\/em><\/strong> (entro il 31 marzo) e la <strong><em>dichiarazione di accessibilit\u00e0<\/em><\/strong> (entro il 23 settembre).<\/li>\n<\/ul>\n<p>Al termine della procedura viene generato un link che rimanda alla pagina obiettivi compilati su <a href=\"http:\/\/accesibilita.agid.gov.it\" target=\"_blank\" rel=\"noopener\">accesibilita.agid.gov.it<\/a> dall\u2019amministrazione.<\/p>\n<p>Il link dev\u2019essere riportato nel sito dell\u2019amministrazione alla pagina Accessibilit\u00e0.<\/p>\n<p>Il luogo e le modalit\u00e0 di pubblicazione degli Obiettivi sono stabiliti dalla delibera ANAC N.50\/2013.<\/p>\n<p><strong>Ma cosa rende un sito web accessibile?<\/strong><\/p>\n<p>Un sito web per essere definito accessibile deve soddisfare determinati criteri e possedere una validazione WCAG (<em>Web Content Accessibility Guidelines<\/em>, ovvero linee guida per l\u2019accessibilit\u00e0 dei siti).<\/p>\n<p>In sostanza deve possedere le seguenti caratteristiche:<\/p>\n<ul>\n<li>Essere <strong>fruibile da normodotati e diversamente abili<\/strong>, indipendentemente dal tipo di disabilit\u00e0.<\/li>\n<li>Essere <strong>navigabile completamente attraverso l\u2019uso del browser web o tecnologie di assistenza<\/strong> (screen reader, tastiere \u201cbraille\u201d o puntatori mouse intelligenti).<\/li>\n<li>Avere <strong>contenuti comprensibili e disposti in gerarchie ordinate<\/strong> in modo da evitare errori durante la navigazione.<\/li>\n<li>Essere <strong>utilizzabile a prescindere dal tipo di dispositivo<\/strong>, sistema operativo, browser o dal contesto di utilizzo.<\/li>\n<li><strong>Fornire le risposte che l\u2019utente sta cercando in modo rapido<\/strong> e preciso, garantendone una buona esperienza di navigazione.<\/li>\n<\/ul>\n<p>L\u2019accessibilit\u00e0 comprende al suo interno tutte le disabilit\u00e0 che influenzano l\u2019accesso alla rete: uditiva, cognitiva, neurologica, fisica, discorsiva e visiva. Ottimizzare un sito web per gli utenti disabili permette di intercettare e soddisfare un segmento di mercato molto pi\u00f9 ampio. Il concetto e i requisiti di accessibilit\u00e0 includono anche il concetto di\u00a0<a href=\"http:\/\/qualitapa.gov.it\/sitoarcheologico\/relazioni-con-i-cittadini\/open-government\/comunicazione-istituzionale-on-line\/portale-pubblico\/internet\/usabilita\/index.html\">usabilit\u00e0<\/a>. Quest\u2019ultima, nella terminologia della legge Stanca, viene indicata con il termine &#8220;fruibilit\u00e0&#8221;. Come previsto dal decreto ministeriale del luglio 2005, l\u2019usabilit\u00e0 viene accertata attraverso la &#8220;verifica soggettiva&#8221;, ovvero mediante una <u>&#8220;valutazione del livello di qualit\u00e0 dei servizi, gi\u00e0 giudicati accessibili tramite la verifica tecnica, effettuata con l\u2019intervento del destinatario, anche disabile, sulla base di considerazioni empiriche&#8221;.<\/u><\/p>\n<p><strong>I 4 principi dell\u2019accessibilit\u00e0<\/strong><\/p>\n<ol>\n<li><strong>PERCEPIBLE<\/strong><\/li>\n<\/ol>\n<p>Ovvero prevede la rimozione di qualsiasi barriera che un utente potrebbe avere per accedere ai contenuti, compresa la possibilit\u00e0 di utilizzare il sito con screen reader, fornendo alternative di testo e una struttura logica.<\/p>\n<ol start=\"2\">\n<li><strong>OPERABLE<\/strong><\/li>\n<\/ol>\n<p>Un sito funzionante e fruibile da tutti gli utenti, a prescindere dal dispositivo su cui stanno navigando, grazie a un lavoro sull\u2019interfaccia utente e sulla navigazione.<\/p>\n<ol start=\"3\">\n<li><strong>COMPRENSIBLE<\/strong><\/li>\n<\/ol>\n<p>Le persone devono essere in grado di comprendere le informazioni visualizzate su una pagina web, nonch\u00e9 comprendere chiaramente l\u2019interfaccia utente.<\/p>\n<ol start=\"4\">\n<li><strong>ROBUST<\/strong><\/li>\n<\/ol>\n<p>Per essere solido, un sito deve poter essere consultato e interpretato da diverse tecnologie e piattaforme, incluso screen reader.<\/p>\n<p>Altri aspetti da tenere a mente per lo sviluppo di un sito che sia \u201caccessibile\u201d sono legati alla parte prettamente visiva, con cui l\u2019utente si interfaccer\u00e0 una volta trovatosi sul sito web.<\/p>\n<ul>\n<li><strong>Colori e contrasto<\/strong>: il colore \u00e8 fondamentale per dare la giusta importanza e rilievo alle informazioni, per\u00f2 non basta. \u00c8 importante anche il contrasto, quindi l\u2019accostamento dei colori per rendere leggibile il sito anche agli utenti daltonici.<\/li>\n<li><strong>Form e moduli<\/strong>: \u00e8 importante assicurarsi che i moduli siano compilabili in ogni loro parte anche dagli utenti con disabilit\u00e0. L\u2019accessibilit\u00e0 pu\u00f2 essere garantita verificando che tutte le etichette siano associate correttamente agli elementi del form.<\/li>\n<li><strong>Testo alternativo<\/strong>: il testo alternativo \u00e8 quel testo che viene visualizzato o letto dagli strumenti di sintesi vocale utilizzati dalle persone cieche quando l\u2019immagine non viene caricata correttamente. Ogni elemento fotografico dovrebbe essere accompagnato da una descrizione o didascalia cos\u00ec da poter rendere il contenuto fruibile a tutti.<\/li>\n<li><strong>Elementi di distrazione<\/strong>: gli elementi di distrazione possono essere tutti quegli elementi che rendono il sito difficilmente accessibile agli utenti che per esempio soffrono di epilessia. Uno di questi elementi potrebbe essere semplicemente lo scorrimento troppo veloce di immagini e testo.<\/li>\n<li><strong>Codice Captcha<\/strong>: CAPTCHA sta per Completely Automated Public Turing test to tell Computers and Humans Apart, ovvero Test di Turing completamente automatizzato e pubblico per distinguere i computer dagli umani. I codici captcha sono molto utili per controllare il problema dello spam ma nelle versioni pi\u00f9 classiche (come a esempio la versione in cui bisogna ricopiare il testo rappresentato in immagine) sono poco accessibili a persone con disabilit\u00e0.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"Le persone con disabilit\u00e0, secondo la pubblicazione ISTAT \u201cConoscere il mondo della disabilit\u00e0\u201d, del 2019, sono 3,1 milioni;&hellip;\n","protected":false},"author":10,"featured_media":112132,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"0","_seopress_titles_title":"","_seopress_titles_desc":"Con il termine accessibilit\u00e0 si intende la possibilit\u00e0 di fruizione dei contenuti web a tutti gli utenti, senza discriminazioni.","_seopress_robots_index":"","csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[227],"tags":[100],"class_list":{"0":"post-112131","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-inova","8":"tag-inova-41","9":"cs-entry","10":"cs-video-wrap"},"_links":{"self":[{"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/posts\/112131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/comments?post=112131"}],"version-history":[{"count":3,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/posts\/112131\/revisions"}],"predecessor-version":[{"id":116229,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/posts\/112131\/revisions\/116229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/media\/112132"}],"wp:attachment":[{"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/media?parent=112131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/categories?post=112131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/studiowiki.it\/inova\/wp-json\/wp\/v2\/tags?post=112131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}